{"id":110,"count":1,"description":"","link":"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/","name":"viticcio","slug":"viticcio","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>viticcio Archivi - Goelba.it<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"viticcio Archivi - Goelba.it\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/\" \/>\n<meta property=\"og:site_name\" content=\"Goelba.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/\",\"url\":\"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/\",\"name\":\"viticcio Archivi - Goelba.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.goelba.it\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.goelba.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"viticcio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goelba.it\/blog\/#website\",\"url\":\"https:\/\/www.goelba.it\/blog\/\",\"name\":\"Goelba.it\",\"description\":\"Quello che c&#039;\u00e8 da sapere per vacanze all&#039;isola d&#039;Elba\",\"publisher\":{\"@id\":\"https:\/\/www.goelba.it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goelba.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.goelba.it\/blog\/#organization\",\"name\":\"GoElba\",\"url\":\"https:\/\/www.goelba.it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.goelba.it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.goelba.it\/blog\/wp-content\/uploads\/2019\/07\/logo.png\",\"contentUrl\":\"https:\/\/www.goelba.it\/blog\/wp-content\/uploads\/2019\/07\/logo.png\",\"width\":394,\"height\":150,\"caption\":\"GoElba\"},\"image\":{\"@id\":\"https:\/\/www.goelba.it\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"viticcio Archivi - Goelba.it","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"viticcio Archivi - Goelba.it","og_url":"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/","og_site_name":"Goelba.it","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/","url":"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/","name":"viticcio Archivi - Goelba.it","isPartOf":{"@id":"https:\/\/www.goelba.it\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.goelba.it\/blog\/tag\/viticcio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.goelba.it\/blog\/"},{"@type":"ListItem","position":2,"name":"viticcio"}]},{"@type":"WebSite","@id":"https:\/\/www.goelba.it\/blog\/#website","url":"https:\/\/www.goelba.it\/blog\/","name":"Goelba.it","description":"Quello che c&#039;\u00e8 da sapere per vacanze all&#039;isola d&#039;Elba","publisher":{"@id":"https:\/\/www.goelba.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goelba.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.goelba.it\/blog\/#organization","name":"GoElba","url":"https:\/\/www.goelba.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.goelba.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.goelba.it\/blog\/wp-content\/uploads\/2019\/07\/logo.png","contentUrl":"https:\/\/www.goelba.it\/blog\/wp-content\/uploads\/2019\/07\/logo.png","width":394,"height":150,"caption":"GoElba"},"image":{"@id":"https:\/\/www.goelba.it\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.goelba.it\/blog\/wp-json\/wp\/v2\/tags\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goelba.it\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.goelba.it\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.goelba.it\/blog\/wp-json\/wp\/v2\/posts?tags=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}